{"id":11548,"date":"2024-06-07T20:00:59","date_gmt":"2024-06-07T17:00:59","guid":{"rendered":"https:\/\/abdullahsakkijha.com\/?page_id=11548"},"modified":"2025-08-14T20:47:40","modified_gmt":"2025-08-14T17:47:40","slug":"asselah-collection","status":"publish","type":"page","link":"https:\/\/abdullahsakkijha.com\/ar\/asselah-collection\/","title":{"rendered":"\u0645\u062c\u0645\u0648\u0639\u0629 \u0623\u0635\u064a\u0644\u0629"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"11548\" class=\"elementor elementor-11548 elementor-11547\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2ad499b elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"2ad499b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-332bfbb\" data-id=\"332bfbb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f967afc elementor-widget elementor-widget-etheme_slider\" data-id=\"f967afc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"etheme_slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"swiper-entry et-slider  slider-7506 etheme-css\" data-css=\".slider-7506 .swiper-custom-left,  .slider-7506 .swiper-custom-right{color:#222 !important;background-color: #e1e1e1 !important} .slider-7506 .swiper-custom-left:hover,  .slider-7506 .swiper-custom-right:hover{background-color: #e1e1e1 !important}\">\n\t\t\t<div class=\"swiper-container \" data-centeredSlides=\"1\" data-breakpoints=\"1\" data-xs-slides=\"1\" data-sm-slides=\"1\" data-md-slides=\"1\" data-lt-slides=\"1\" data-slides-per-view=\"1\" data-space=\"0\" data-autoplay=\"\" data-speed=\"300\" data-effect=\"slide\">\n\t\t\t\t<div class=\"et-loader swiper-lazy-preloader\"><\/div>\n\t\t\t\t<!-- Additional required wrapper -->\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t<!-- Slides -->\n\t\t\t\t\t<div class=\"swiper-slide\">\t\t<div class=\"slider-item  fadeIn-slide slider-item-7120  elementor-repeater-item-bbcde6e\" data-slide-id=\"7120\">\n\n\t\t\t\t\t\t\n\t\t\t<div class=\"container  justify-content-center align-items-center\">\n\n\t\t\t\t<div class=\"slide-content \">\n\n\t\t\t\t\t<h2 class=\"slide-title  animated\">\u0645\u062c\u0645\u0648\u0639\u0629 \u0623\u0635\u064a\u0644\u0629<\/h2><h2 class=\"slide-subtitle  animated\"><\/h2>\n\t\t\t\t\t<div class=\"description animated\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\n\t\t\t\t<\/div> \n\t\t\t<\/div> \n\t   \t<\/div> \t    \n\t    <\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7f7f5ff elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7f7f5ff\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e7e5f5f\" data-id=\"e7e5f5f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-24cbd64 hide-price elementor-widget elementor-widget-etheme_products\" data-id=\"24cbd64\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"etheme_products.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <link rel=\"stylesheet\" href=\"https:\/\/abdullahsakkijha.com\/wp-content\/themes\/xstore\/css\/modules\/woocommerce\/product-hovers\/product-view-default.min.css?ver=1.0.0\" type=\"text\/css\" media=\"all\" \/> \t\t<div class=\"etheme_products etheme_products-r159 \" >\t\t\t\t<div class=\"row products products-loop products-grid row-count-4\" data-row-count=\"4\">\n\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t \t<div class=\"first grid-sizer wishlist-disabled col-md-3 col-sm-6 col-xs-6 product-hover-slider product-view-mask view-color-white arrows-hovered et_cart-on hide-hover-on-mobile product type-product post-12251 status-publish instock product_cat-necklaces-ar product_cat-shop-all-ar has-post-thumbnail shipping-taxable purchasable product-type-simple\">\n        \t\t<div class=\"content-product \">\n\t\t\t\n\t\t\t\n\t\t\t\t<div class=\"product-image-wrapper hover-effect-slider\"\n                    >\n\n\t\t\t\t\t\t\t\t\t\t<div class=\"images-slider-wrapper\">                        <a class=\"product-content-image woocommerce-LoopProduct-link woocommerce-loop-product__link\" href=\"https:\/\/abdullahsakkijha.com\/ar\/shop\/necklaces-ar\/aseelah-necklace\/\"\n                           data-images=\"https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2024\/07\/asselahnecklace-300x300.jpg;https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2024\/07\/asselahnecklace01-300x300.jpg\"\n                        >\n                            <img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"Aseelah Necklace\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-src=\"https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2024\/07\/asselahnecklace-300x300.jpg\" data-srcset=\"https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2024\/07\/asselahnecklace-300x300.jpg 300w, https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2024\/07\/asselahnecklace-1024x1024.jpg 1024w, https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2024\/07\/asselahnecklace-150x150.jpg 150w, https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2024\/07\/asselahnecklace-768x768.jpg 768w, https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2024\/07\/asselahnecklace-100x100.jpg 100w, https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2024\/07\/asselahnecklace-1x1.jpg 1w, https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2024\/07\/asselahnecklace-10x10.jpg 10w, https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2024\/07\/asselahnecklace.jpg 1080w\" \/>                        <\/a>\n\t\t\t\t\t<\/div>\t\t\t\t\t\t<footer class=\"footer-product\">\n                            <\/a><a href=\"\/ar\/wp-json\/wp\/v2\/pages\/11548?add-to-cart=12251\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12251\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"12251\" data-product_sku=\"\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Aseelah Necklace&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Aseelah Necklace&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" data-product_name=\"Aseelah Necklace\" role=\"button\">\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12251\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n                            \t\t\t\t\t\t<\/footer>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t\t\t<div class=\"text-center product-details\"><div class=\"products-page-cats\"><a href=\"https:\/\/abdullahsakkijha.com\/ar\/product-category\/necklaces-ar\/\">\u0627\u0644\u0642\u0644\u0627\u062f\u0627\u062a<\/a><\/div>\t\t\t\t\t\t\t<h2 class=\"product-title\">\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/abdullahsakkijha.com\/ar\/shop\/necklaces-ar\/aseelah-necklace\/\">Aseelah Necklace<\/a>\n                            <\/h2>\n\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>0&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#36;<\/span><\/bdi><\/span><\/span>\n\n\t\t\t\t\t\t\n                        \n                                        <\/div>\n\t\t\t\t\t\t\t\t\t         \t\t<\/div><!-- .content-product -->\n\t<\/div>\n\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t \t<div class=\"wishlist-disabled col-md-3 col-sm-6 col-xs-6 product-hover-slider product-view-mask view-color-white arrows-hovered et_cart-on hide-hover-on-mobile product type-product post-7906 status-publish last instock product_cat-necklaces-ar product_cat-shop-all-ar has-post-thumbnail shipping-taxable purchasable product-type-simple\">\n        \t\t<div class=\"content-product \">\n\t\t\t\n\t\t\t\n\t\t\t\t<div class=\"product-image-wrapper hover-effect-slider\"\n                    >\n\n\t\t\t\t\t\t\t\t\t\t<div class=\"images-slider-wrapper\">                        <a class=\"product-content-image woocommerce-LoopProduct-link woocommerce-loop-product__link\" href=\"https:\/\/abdullahsakkijha.com\/ar\/shop\/necklaces-ar\/aseelah-necklace-05\/\"\n                           data-images=\"https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2022\/11\/6200\ufffd_necklace1-min-300x300.jpg;https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2022\/11\/6200\ufffd_necklace2-min-300x300.jpg\"\n                        >\n                            <img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"Aseelah Necklace\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-src=\"https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2022\/11\/6200\ufffd_necklace1-min-300x300.jpg\" data-srcset=\"https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2022\/11\/6200\ufffd_necklace1-min-300x300.jpg 300w, https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2022\/11\/6200\ufffd_necklace1-min-100x100.jpg 100w, https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2022\/11\/6200\ufffd_necklace1-min-416x416.jpg 416w, https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2022\/11\/6200\ufffd_necklace1-min-150x150.jpg 150w, https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2022\/11\/6200\ufffd_necklace1-min-768x768.jpg 768w, https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2022\/11\/6200\ufffd_necklace1-min-1x1.jpg 1w, https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2022\/11\/6200\ufffd_necklace1-min-10x10.jpg 10w, https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2022\/11\/6200\ufffd_necklace1-min.jpg 1000w\" \/>                        <\/a>\n\t\t\t\t\t<\/div>\t\t\t\t\t\t<footer class=\"footer-product\">\n                            <\/a><a href=\"\/ar\/wp-json\/wp\/v2\/pages\/11548?add-to-cart=7906\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_7906\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"7906\" data-product_sku=\"\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Aseelah Necklace&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Aseelah Necklace&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" data-product_name=\"Aseelah Necklace\" role=\"button\">\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_7906\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n                            \t\t\t\t\t\t<\/footer>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t\t\t<div class=\"text-center product-details\"><div class=\"products-page-cats\"><a href=\"https:\/\/abdullahsakkijha.com\/ar\/product-category\/bracelets-ar\/\">\u0627\u0644\u0623\u0633\u0627\u0648\u0631<\/a><\/div>\t\t\t\t\t\t\t<h2 class=\"product-title\">\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/abdullahsakkijha.com\/ar\/shop\/necklaces-ar\/aseelah-necklace-05\/\">Aseelah Necklace<\/a>\n                            <\/h2>\n\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>0&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#36;<\/span><\/bdi><\/span><\/span>\n\n\t\t\t\t\t\t\n                        \n                                        <\/div>\n\t\t\t\t\t\t\t\t\t         \t\t<\/div><!-- .content-product -->\n\t<\/div>\n\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t \t<div class=\"first grid-sizer wishlist-disabled col-md-3 col-sm-6 col-xs-6 product-hover-slider product-view-mask view-color-white arrows-hovered et_cart-on hide-hover-on-mobile product type-product post-7896 status-publish instock product_cat-necklaces-ar product_cat-shop-all-ar has-post-thumbnail shipping-taxable purchasable product-type-variable\">\n        \t\t<div class=\"content-product \">\n\t\t\t\n\t\t\t\n\t\t\t\t<div class=\"product-image-wrapper hover-effect-slider\"\n                    >\n\n\t\t\t\t\t\t\t\t\t\t<div class=\"images-slider-wrapper\">                        <a class=\"product-content-image woocommerce-LoopProduct-link woocommerce-loop-product__link\" href=\"https:\/\/abdullahsakkijha.com\/ar\/shop\/necklaces-ar\/aseelah-necklace-04\/\"\n                           data-images=\"\"\n                        >\n                            <img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"Aseelah Necklace\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-src=\"https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2022\/11\/5600\ufffd_necklace2-min-300x300.jpg\" data-srcset=\"https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2022\/11\/5600\ufffd_necklace2-min-300x300.jpg 300w, https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2022\/11\/5600\ufffd_necklace2-min-100x100.jpg 100w, https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2022\/11\/5600\ufffd_necklace2-min-416x416.jpg 416w, https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2022\/11\/5600\ufffd_necklace2-min-150x150.jpg 150w, https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2022\/11\/5600\ufffd_necklace2-min-768x768.jpg 768w, https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2022\/11\/5600\ufffd_necklace2-min-1x1.jpg 1w, https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2022\/11\/5600\ufffd_necklace2-min-10x10.jpg 10w, https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2022\/11\/5600\ufffd_necklace2-min.jpg 1000w\" \/>                        <\/a>\n\t\t\t\t\t<\/div>\t\t\t\t\t\t<footer class=\"footer-product\">\n                            <\/a><a href=\"https:\/\/abdullahsakkijha.com\/ar\/shop\/necklaces-ar\/aseelah-necklace-04\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_7896\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"7896\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Aseelah Necklace&quot;\" rel=\"nofollow\" data-product_name=\"Aseelah Necklace\">\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_7896\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n                            \t\t\t\t\t\t<\/footer>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t\t\t<div class=\"text-center product-details\"><div class=\"products-page-cats\"><a href=\"https:\/\/abdullahsakkijha.com\/ar\/product-category\/necklaces-ar\/\">\u0627\u0644\u0642\u0644\u0627\u062f\u0627\u062a<\/a><\/div>\t\t\t\t\t\t\t<h2 class=\"product-title\">\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/abdullahsakkijha.com\/ar\/shop\/necklaces-ar\/aseelah-necklace-04\/\">Aseelah Necklace<\/a>\n                            <\/h2>\n\t\t\t\t\t\t\n\n\t\t\t\t\t\t\n                        \n                                        <\/div>\n\t\t\t\t\t\t\t\t\t         \t\t<\/div><!-- .content-product -->\n\t<\/div>\n\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t \t<div class=\"wishlist-disabled col-md-3 col-sm-6 col-xs-6 product-hover-slider product-view-mask view-color-white arrows-hovered et_cart-on hide-hover-on-mobile product type-product post-7181 status-publish last instock product_cat-necklaces-ar product_cat-shop-all-ar has-post-thumbnail shipping-taxable purchasable product-type-simple\">\n        \t\t<div class=\"content-product \">\n\t\t\t\n\t\t\t\n\t\t\t\t<div class=\"product-image-wrapper hover-effect-slider\"\n                    >\n\n\t\t\t\t\t\t\t\t\t\t<div class=\"images-slider-wrapper\">                        <a class=\"product-content-image woocommerce-LoopProduct-link woocommerce-loop-product__link\" href=\"https:\/\/abdullahsakkijha.com\/ar\/shop\/necklaces-ar\/aseelah-necklace-03\/\"\n                           data-images=\"\"\n                        >\n                            <img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"Aseelah Necklace\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-src=\"https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2023\/01\/Aseelah-Necklace-4-300x300.jpg\" data-srcset=\"https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2023\/01\/Aseelah-Necklace-4-300x300.jpg 300w, https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2023\/01\/Aseelah-Necklace-4-1024x1024.jpg 1024w, https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2023\/01\/Aseelah-Necklace-4-150x150.jpg 150w, https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2023\/01\/Aseelah-Necklace-4-768x768.jpg 768w, https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2023\/01\/Aseelah-Necklace-4-100x100.jpg 100w, https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2023\/01\/Aseelah-Necklace-4-1x1.jpg 1w, https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2023\/01\/Aseelah-Necklace-4-10x10.jpg 10w, https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2023\/01\/Aseelah-Necklace-4.jpg 1080w\" \/>                        <\/a>\n\t\t\t\t\t<\/div>\t\t\t\t\t\t<footer class=\"footer-product\">\n                            <\/a><a href=\"\/ar\/wp-json\/wp\/v2\/pages\/11548?add-to-cart=7181\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_7181\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"7181\" data-product_sku=\"\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Aseelah Necklace&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Aseelah Necklace&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" data-product_name=\"Aseelah Necklace\" role=\"button\">\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_7181\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n                            \t\t\t\t\t\t<\/footer>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t\t\t<div class=\"text-center product-details\"><div class=\"products-page-cats\"><a href=\"https:\/\/abdullahsakkijha.com\/ar\/product-category\/necklaces-ar\/\">\u0627\u0644\u0642\u0644\u0627\u062f\u0627\u062a<\/a><\/div>\t\t\t\t\t\t\t<h2 class=\"product-title\">\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/abdullahsakkijha.com\/ar\/shop\/necklaces-ar\/aseelah-necklace-03\/\">Aseelah Necklace<\/a>\n                            <\/h2>\n\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>0&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#36;<\/span><\/bdi><\/span><\/span>\n\n\t\t\t\t\t\t\n                        \n                                        <\/div>\n\t\t\t\t\t\t\t\t\t         \t\t<\/div><!-- .content-product -->\n\t<\/div>\n\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t \t<div class=\"first grid-sizer wishlist-disabled col-md-3 col-sm-6 col-xs-6 product-hover-slider product-view-mask view-color-white arrows-hovered et_cart-on hide-hover-on-mobile product type-product post-7491 status-publish instock product_cat-necklaces-ar product_cat-shop-all-ar has-post-thumbnail shipping-taxable purchasable product-type-simple\">\n        \t\t<div class=\"content-product \">\n\t\t\t\n\t\t\t\n\t\t\t\t<div class=\"product-image-wrapper hover-effect-slider\"\n                    >\n\n\t\t\t\t\t\t\t\t\t\t<div class=\"images-slider-wrapper\">                        <a class=\"product-content-image woocommerce-LoopProduct-link woocommerce-loop-product__link\" href=\"https:\/\/abdullahsakkijha.com\/ar\/shop\/necklaces-ar\/aseelah-necklace-02\/\"\n                           data-images=\"\"\n                        >\n                            <img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"Aseelah Necklace\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-src=\"https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2023\/01\/Aseelah-Necklace-3-300x300.jpg\" data-srcset=\"https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2023\/01\/Aseelah-Necklace-3-300x300.jpg 300w, https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2023\/01\/Aseelah-Necklace-3-1024x1024.jpg 1024w, https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2023\/01\/Aseelah-Necklace-3-150x150.jpg 150w, https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2023\/01\/Aseelah-Necklace-3-768x768.jpg 768w, https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2023\/01\/Aseelah-Necklace-3-100x100.jpg 100w, https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2023\/01\/Aseelah-Necklace-3-1x1.jpg 1w, https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2023\/01\/Aseelah-Necklace-3-10x10.jpg 10w, https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2023\/01\/Aseelah-Necklace-3.jpg 1080w\" \/>                        <\/a>\n\t\t\t\t\t<\/div>\t\t\t\t\t\t<footer class=\"footer-product\">\n                            <\/a><a href=\"\/ar\/wp-json\/wp\/v2\/pages\/11548?add-to-cart=7491\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_7491\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"7491\" data-product_sku=\"\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Aseelah Necklace&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Aseelah Necklace&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" data-product_name=\"Aseelah Necklace\" role=\"button\">\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_7491\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n                            \t\t\t\t\t\t<\/footer>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t\t\t<div class=\"text-center product-details\"><div class=\"products-page-cats\"><a href=\"https:\/\/abdullahsakkijha.com\/ar\/product-category\/necklaces-ar\/\">\u0627\u0644\u0642\u0644\u0627\u062f\u0627\u062a<\/a><\/div>\t\t\t\t\t\t\t<h2 class=\"product-title\">\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/abdullahsakkijha.com\/ar\/shop\/necklaces-ar\/aseelah-necklace-02\/\">Aseelah Necklace<\/a>\n                            <\/h2>\n\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>0&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#36;<\/span><\/bdi><\/span><\/span>\n\n\t\t\t\t\t\t\n                        \n                                        <\/div>\n\t\t\t\t\t\t\t\t\t         \t\t<\/div><!-- .content-product -->\n\t<\/div>\n\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t \t<div class=\"wishlist-disabled col-md-3 col-sm-6 col-xs-6 product-hover-slider product-view-mask view-color-white arrows-hovered et_cart-on hide-hover-on-mobile product type-product post-7492 status-publish last instock product_cat-necklaces-ar product_cat-shop-all-ar has-post-thumbnail shipping-taxable purchasable product-type-simple\">\n        \t\t<div class=\"content-product \">\n\t\t\t\n\t\t\t\n\t\t\t\t<div class=\"product-image-wrapper hover-effect-slider\"\n                    >\n\n\t\t\t\t\t\t\t\t\t\t<div class=\"images-slider-wrapper\">                        <a class=\"product-content-image woocommerce-LoopProduct-link woocommerce-loop-product__link\" href=\"https:\/\/abdullahsakkijha.com\/ar\/shop\/necklaces-ar\/aseelah-necklace-01\/\"\n                           data-images=\"\"\n                        >\n                            <img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"Aseelah Necklace\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-src=\"https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2023\/01\/Aseelah-Necklace-2-300x300.jpg\" data-srcset=\"https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2023\/01\/Aseelah-Necklace-2-300x300.jpg 300w, https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2023\/01\/Aseelah-Necklace-2-1024x1024.jpg 1024w, https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2023\/01\/Aseelah-Necklace-2-150x150.jpg 150w, https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2023\/01\/Aseelah-Necklace-2-768x768.jpg 768w, https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2023\/01\/Aseelah-Necklace-2-100x100.jpg 100w, https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2023\/01\/Aseelah-Necklace-2-1x1.jpg 1w, https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2023\/01\/Aseelah-Necklace-2-10x10.jpg 10w, https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2023\/01\/Aseelah-Necklace-2.jpg 1080w\" \/>                        <\/a>\n\t\t\t\t\t<\/div>\t\t\t\t\t\t<footer class=\"footer-product\">\n                            <\/a><a href=\"\/ar\/wp-json\/wp\/v2\/pages\/11548?add-to-cart=7492\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_7492\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"7492\" data-product_sku=\"\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Aseelah Necklace&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Aseelah Necklace&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" data-product_name=\"Aseelah Necklace\" role=\"button\">\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_7492\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n                            \t\t\t\t\t\t<\/footer>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t\t\t<div class=\"text-center product-details\"><div class=\"products-page-cats\"><a href=\"https:\/\/abdullahsakkijha.com\/ar\/product-category\/necklaces-ar\/\">\u0627\u0644\u0642\u0644\u0627\u062f\u0627\u062a<\/a><\/div>\t\t\t\t\t\t\t<h2 class=\"product-title\">\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/abdullahsakkijha.com\/ar\/shop\/necklaces-ar\/aseelah-necklace-01\/\">Aseelah Necklace<\/a>\n                            <\/h2>\n\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>0&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#36;<\/span><\/bdi><\/span><\/span>\n\n\t\t\t\t\t\t\n                        \n                                        <\/div>\n\t\t\t\t\t\t\t\t\t         \t\t<\/div><!-- .content-product -->\n\t<\/div>\n\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t \t<div class=\"first grid-sizer wishlist-disabled col-md-3 col-sm-6 col-xs-6 product-hover-slider product-view-mask view-color-white arrows-hovered et_cart-on hide-hover-on-mobile product type-product post-7493 status-publish instock product_cat-necklaces-ar product_cat-shop-all-ar has-post-thumbnail shipping-taxable purchasable product-type-simple\">\n        \t\t<div class=\"content-product \">\n\t\t\t\n\t\t\t\n\t\t\t\t<div class=\"product-image-wrapper hover-effect-slider\"\n                    >\n\n\t\t\t\t\t\t\t\t\t\t<div class=\"images-slider-wrapper\">                        <a class=\"product-content-image woocommerce-LoopProduct-link woocommerce-loop-product__link\" href=\"https:\/\/abdullahsakkijha.com\/ar\/shop\/necklaces-ar\/aseelah-necklace-00\/\"\n                           data-images=\"\"\n                        >\n                            <img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/xstore\/xstore-placeholder-1x1.png\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"Aseelah Necklace\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-src=\"https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2023\/01\/Aseelah-Necklace-1-300x300.jpg\" data-srcset=\"https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2023\/01\/Aseelah-Necklace-1-300x300.jpg 300w, https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2023\/01\/Aseelah-Necklace-1-1024x1024.jpg 1024w, https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2023\/01\/Aseelah-Necklace-1-150x150.jpg 150w, https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2023\/01\/Aseelah-Necklace-1-768x768.jpg 768w, https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2023\/01\/Aseelah-Necklace-1-100x100.jpg 100w, https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2023\/01\/Aseelah-Necklace-1-1x1.jpg 1w, https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2023\/01\/Aseelah-Necklace-1-10x10.jpg 10w, https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2023\/01\/Aseelah-Necklace-1.jpg 1080w\" \/>                        <\/a>\n\t\t\t\t\t<\/div>\t\t\t\t\t\t<footer class=\"footer-product\">\n                            <\/a><a href=\"\/ar\/wp-json\/wp\/v2\/pages\/11548?add-to-cart=7493\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_7493\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"7493\" data-product_sku=\"\" aria-label=\"\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642: &quot;Aseelah Necklace&quot;\" rel=\"nofollow\" data-success_message=\"\u062a\u0645\u062a \u0625\u0636\u0627\u0641\u0629 &quot;Aseelah Necklace&quot; \u0625\u0644\u0649 \u0639\u0631\u0628\u0629 \u0627\u0644\u062a\u0633\u0648\u0642 \u0644\u062f\u064a\u0643\" data-product_name=\"Aseelah Necklace\" role=\"button\">\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0633\u0644\u0629<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_7493\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n                            \t\t\t\t\t\t<\/footer>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t\t\t<div class=\"text-center product-details\"><div class=\"products-page-cats\"><a href=\"https:\/\/abdullahsakkijha.com\/ar\/product-category\/necklaces-ar\/\">\u0627\u0644\u0642\u0644\u0627\u062f\u0627\u062a<\/a><\/div>\t\t\t\t\t\t\t<h2 class=\"product-title\">\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/abdullahsakkijha.com\/ar\/shop\/necklaces-ar\/aseelah-necklace-00\/\">Aseelah Necklace<\/a>\n                            <\/h2>\n\t\t\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>0&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&#36;<\/span><\/bdi><\/span><\/span>\n\n\t\t\t\t\t\t\n                        \n                                        <\/div>\n\t\t\t\t\t\t\t\t\t         \t\t<\/div><!-- .content-product -->\n\t<\/div>\n\n\t\t\t\t\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t<\/div> <!-- .row -->\t\t\t\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Token tabanl\u0131 oyun pop\u00fcler hale geliyor. Kumarhane \u00f6d\u00fclleri kat\u0131l\u0131m\u0131 art\u0131r\u0131r,&#8230;<\/p>\n","protected":false},"author":333,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-11548","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0645\u062c\u0645\u0648\u0639\u0629 \u0623\u0635\u064a\u0644\u0629 | \u0645\u062c\u0648\u0647\u0631\u0627\u062a \u0639\u0628\u062f \u0627\u0644\u0644\u0647 \u0633\u0643\u062c\u0647\u0627<\/title>\n<meta name=\"description\" content=\"\u0645\u062c\u0648\u0647\u0631\u0627\u062a \u0639\u0628\u062f \u0627\u0644\u0644\u0647 \u0633\u0643\u062c\u0647\u0627 - \u0627\u0633\u0645 \u062a\u062b\u0642 \u0628\u0647 \u0627\u0644\u0623\u062c\u064a\u0627\u0644. \u0625\u062d\u062f\u0649 \u0627\u0644\u0639\u0644\u0627\u0645\u0627\u062a \u0627\u0644\u062a\u062c\u0627\u0631\u064a\u0629 \u0627\u0644\u0631\u0627\u0626\u062f\u0629 \u0641\u064a \u0645\u062c\u0627\u0644 \u0627\u0644\u0645\u062c\u0648\u0647\u0631\u0627\u062a \u0641\u064a \u0627\u0644\u0623\u0631\u062f\u0646 \u0648\u0627\u0644\u0645\u0646\u0637\u0642\u0629.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/abdullahsakkijha.com\/asselah-collection\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0645\u062c\u0645\u0648\u0639\u0629 \u0623\u0635\u064a\u0644\u0629 | \u0645\u062c\u0648\u0647\u0631\u0627\u062a \u0639\u0628\u062f \u0627\u0644\u0644\u0647 \u0633\u0643\u062c\u0647\u0627\" \/>\n<meta property=\"og:description\" content=\"\u0645\u062c\u0648\u0647\u0631\u0627\u062a \u0639\u0628\u062f \u0627\u0644\u0644\u0647 \u0633\u0643\u062c\u0647\u0627 - \u0627\u0633\u0645 \u062a\u062b\u0642 \u0628\u0647 \u0627\u0644\u0623\u062c\u064a\u0627\u0644. \u0625\u062d\u062f\u0649 \u0627\u0644\u0639\u0644\u0627\u0645\u0627\u062a \u0627\u0644\u062a\u062c\u0627\u0631\u064a\u0629 \u0627\u0644\u0631\u0627\u0626\u062f\u0629 \u0641\u064a \u0645\u062c\u0627\u0644 \u0627\u0644\u0645\u062c\u0648\u0647\u0631\u0627\u062a \u0641\u064a \u0627\u0644\u0623\u0631\u062f\u0646 \u0648\u0627\u0644\u0645\u0646\u0637\u0642\u0629.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/abdullahsakkijha.com\/asselah-collection\/\" \/>\n<meta property=\"og:site_name\" content=\"Abdullah Sakkijha\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/abdullah.sakkijha\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-14T17:47:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2024\/07\/asselahnecklace-300x300.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@abdullahsakijha\" \/>\n<meta name=\"twitter:label1\" content=\"\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u062f\u0642\u064a\u0642\u062a\u0627\u0646\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/abdullahsakkijha.com\\\/asselah-collection\\\/\",\"url\":\"https:\\\/\\\/abdullahsakkijha.com\\\/asselah-collection\\\/\",\"name\":\"\u0645\u062c\u0645\u0648\u0639\u0629 \u0623\u0635\u064a\u0644\u0629 | \u0645\u062c\u0648\u0647\u0631\u0627\u062a \u0639\u0628\u062f \u0627\u0644\u0644\u0647 \u0633\u0643\u062c\u0647\u0627\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/abdullahsakkijha.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/abdullahsakkijha.com\\\/asselah-collection\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/abdullahsakkijha.com\\\/asselah-collection\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/abdullahsakkijha.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/asselahnecklace-300x300.jpg\",\"datePublished\":\"2024-06-07T17:00:59+00:00\",\"dateModified\":\"2025-08-14T17:47:40+00:00\",\"description\":\"\u0645\u062c\u0648\u0647\u0631\u0627\u062a \u0639\u0628\u062f \u0627\u0644\u0644\u0647 \u0633\u0643\u062c\u0647\u0627 - \u0627\u0633\u0645 \u062a\u062b\u0642 \u0628\u0647 \u0627\u0644\u0623\u062c\u064a\u0627\u0644. \u0625\u062d\u062f\u0649 \u0627\u0644\u0639\u0644\u0627\u0645\u0627\u062a \u0627\u0644\u062a\u062c\u0627\u0631\u064a\u0629 \u0627\u0644\u0631\u0627\u0626\u062f\u0629 \u0641\u064a \u0645\u062c\u0627\u0644 \u0627\u0644\u0645\u062c\u0648\u0647\u0631\u0627\u062a \u0641\u064a \u0627\u0644\u0623\u0631\u062f\u0646 \u0648\u0627\u0644\u0645\u0646\u0637\u0642\u0629.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/abdullahsakkijha.com\\\/asselah-collection\\\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/abdullahsakkijha.com\\\/asselah-collection\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/abdullahsakkijha.com\\\/asselah-collection\\\/#primaryimage\",\"url\":\"https:\\\/\\\/abdullahsakkijha.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/asselahnecklace-300x300.jpg\",\"contentUrl\":\"https:\\\/\\\/abdullahsakkijha.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/asselahnecklace-300x300.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/abdullahsakkijha.com\\\/asselah-collection\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/abdullahsakkijha.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0645\u062c\u0645\u0648\u0639\u0629 \u0623\u0635\u064a\u0644\u0629\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/abdullahsakkijha.com\\\/#website\",\"url\":\"https:\\\/\\\/abdullahsakkijha.com\\\/\",\"name\":\"Abdullah Sakkijha\",\"description\":\"The Best Jewelry Store in The World\",\"publisher\":{\"@id\":\"https:\\\/\\\/abdullahsakkijha.com\\\/#organization\"},\"alternateName\":\"Abdullah Sakkijha Jewelry\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/abdullahsakkijha.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/abdullahsakkijha.com\\\/#organization\",\"name\":\"Abdullah Sakkijha\",\"alternateName\":\"Abdullah Sakkijha Jewelry\",\"url\":\"https:\\\/\\\/abdullahsakkijha.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/abdullahsakkijha.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/abdullahsakkijha.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logo.svg\",\"contentUrl\":\"https:\\\/\\\/abdullahsakkijha.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Logo.svg\",\"caption\":\"Abdullah Sakkijha\"},\"image\":{\"@id\":\"https:\\\/\\\/abdullahsakkijha.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/abdullah.sakkijha\",\"https:\\\/\\\/x.com\\\/abdullahsakijha\",\"https:\\\/\\\/www.instagram.com\\\/abdullahsakkijhajewelry\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@abdullahsakkijhajewelry\",\"https:\\\/\\\/www.reddit.com\\\/user\\\/abdullahsakkijha\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/abdullahsakkijhajewelry\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/abdullahsakkijhajewelry\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0645\u062c\u0645\u0648\u0639\u0629 \u0623\u0635\u064a\u0644\u0629 | \u0645\u062c\u0648\u0647\u0631\u0627\u062a \u0639\u0628\u062f \u0627\u0644\u0644\u0647 \u0633\u0643\u062c\u0647\u0627","description":"\u0645\u062c\u0648\u0647\u0631\u0627\u062a \u0639\u0628\u062f \u0627\u0644\u0644\u0647 \u0633\u0643\u062c\u0647\u0627 - \u0627\u0633\u0645 \u062a\u062b\u0642 \u0628\u0647 \u0627\u0644\u0623\u062c\u064a\u0627\u0644. \u0625\u062d\u062f\u0649 \u0627\u0644\u0639\u0644\u0627\u0645\u0627\u062a \u0627\u0644\u062a\u062c\u0627\u0631\u064a\u0629 \u0627\u0644\u0631\u0627\u0626\u062f\u0629 \u0641\u064a \u0645\u062c\u0627\u0644 \u0627\u0644\u0645\u062c\u0648\u0647\u0631\u0627\u062a \u0641\u064a \u0627\u0644\u0623\u0631\u062f\u0646 \u0648\u0627\u0644\u0645\u0646\u0637\u0642\u0629.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/abdullahsakkijha.com\/asselah-collection\/","og_locale":"ar_AR","og_type":"article","og_title":"\u0645\u062c\u0645\u0648\u0639\u0629 \u0623\u0635\u064a\u0644\u0629 | \u0645\u062c\u0648\u0647\u0631\u0627\u062a \u0639\u0628\u062f \u0627\u0644\u0644\u0647 \u0633\u0643\u062c\u0647\u0627","og_description":"\u0645\u062c\u0648\u0647\u0631\u0627\u062a \u0639\u0628\u062f \u0627\u0644\u0644\u0647 \u0633\u0643\u062c\u0647\u0627 - \u0627\u0633\u0645 \u062a\u062b\u0642 \u0628\u0647 \u0627\u0644\u0623\u062c\u064a\u0627\u0644. \u0625\u062d\u062f\u0649 \u0627\u0644\u0639\u0644\u0627\u0645\u0627\u062a \u0627\u0644\u062a\u062c\u0627\u0631\u064a\u0629 \u0627\u0644\u0631\u0627\u0626\u062f\u0629 \u0641\u064a \u0645\u062c\u0627\u0644 \u0627\u0644\u0645\u062c\u0648\u0647\u0631\u0627\u062a \u0641\u064a \u0627\u0644\u0623\u0631\u062f\u0646 \u0648\u0627\u0644\u0645\u0646\u0637\u0642\u0629.","og_url":"https:\/\/abdullahsakkijha.com\/asselah-collection\/","og_site_name":"Abdullah Sakkijha","article_publisher":"https:\/\/www.facebook.com\/abdullah.sakkijha","article_modified_time":"2025-08-14T17:47:40+00:00","og_image":[{"url":"https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2024\/07\/asselahnecklace-300x300.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@abdullahsakijha","twitter_misc":{"\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631":"\u062f\u0642\u064a\u0642\u062a\u0627\u0646"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/abdullahsakkijha.com\/asselah-collection\/","url":"https:\/\/abdullahsakkijha.com\/asselah-collection\/","name":"\u0645\u062c\u0645\u0648\u0639\u0629 \u0623\u0635\u064a\u0644\u0629 | \u0645\u062c\u0648\u0647\u0631\u0627\u062a \u0639\u0628\u062f \u0627\u0644\u0644\u0647 \u0633\u0643\u062c\u0647\u0627","isPartOf":{"@id":"https:\/\/abdullahsakkijha.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/abdullahsakkijha.com\/asselah-collection\/#primaryimage"},"image":{"@id":"https:\/\/abdullahsakkijha.com\/asselah-collection\/#primaryimage"},"thumbnailUrl":"https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2024\/07\/asselahnecklace-300x300.jpg","datePublished":"2024-06-07T17:00:59+00:00","dateModified":"2025-08-14T17:47:40+00:00","description":"\u0645\u062c\u0648\u0647\u0631\u0627\u062a \u0639\u0628\u062f \u0627\u0644\u0644\u0647 \u0633\u0643\u062c\u0647\u0627 - \u0627\u0633\u0645 \u062a\u062b\u0642 \u0628\u0647 \u0627\u0644\u0623\u062c\u064a\u0627\u0644. \u0625\u062d\u062f\u0649 \u0627\u0644\u0639\u0644\u0627\u0645\u0627\u062a \u0627\u0644\u062a\u062c\u0627\u0631\u064a\u0629 \u0627\u0644\u0631\u0627\u0626\u062f\u0629 \u0641\u064a \u0645\u062c\u0627\u0644 \u0627\u0644\u0645\u062c\u0648\u0647\u0631\u0627\u062a \u0641\u064a \u0627\u0644\u0623\u0631\u062f\u0646 \u0648\u0627\u0644\u0645\u0646\u0637\u0642\u0629.","breadcrumb":{"@id":"https:\/\/abdullahsakkijha.com\/asselah-collection\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/abdullahsakkijha.com\/asselah-collection\/"]}]},{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/abdullahsakkijha.com\/asselah-collection\/#primaryimage","url":"https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2024\/07\/asselahnecklace-300x300.jpg","contentUrl":"https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2024\/07\/asselahnecklace-300x300.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/abdullahsakkijha.com\/asselah-collection\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/abdullahsakkijha.com\/"},{"@type":"ListItem","position":2,"name":"\u0645\u062c\u0645\u0648\u0639\u0629 \u0623\u0635\u064a\u0644\u0629"}]},{"@type":"WebSite","@id":"https:\/\/abdullahsakkijha.com\/#website","url":"https:\/\/abdullahsakkijha.com\/","name":"Abdullah Sakkijha","description":"The Best Jewelry Store in The World","publisher":{"@id":"https:\/\/abdullahsakkijha.com\/#organization"},"alternateName":"Abdullah Sakkijha Jewelry","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/abdullahsakkijha.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Organization","@id":"https:\/\/abdullahsakkijha.com\/#organization","name":"Abdullah Sakkijha","alternateName":"Abdullah Sakkijha Jewelry","url":"https:\/\/abdullahsakkijha.com\/","logo":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/abdullahsakkijha.com\/#\/schema\/logo\/image\/","url":"https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2024\/02\/Logo.svg","contentUrl":"https:\/\/abdullahsakkijha.com\/wp-content\/uploads\/2024\/02\/Logo.svg","caption":"Abdullah Sakkijha"},"image":{"@id":"https:\/\/abdullahsakkijha.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/abdullah.sakkijha","https:\/\/x.com\/abdullahsakijha","https:\/\/www.instagram.com\/abdullahsakkijhajewelry\/","https:\/\/www.youtube.com\/@abdullahsakkijhajewelry","https:\/\/www.reddit.com\/user\/abdullahsakkijha\/","https:\/\/www.pinterest.com\/abdullahsakkijhajewelry\/","https:\/\/www.linkedin.com\/company\/abdullahsakkijhajewelry\/"]}]}},"_links":{"self":[{"href":"https:\/\/abdullahsakkijha.com\/ar\/wp-json\/wp\/v2\/pages\/11548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/abdullahsakkijha.com\/ar\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/abdullahsakkijha.com\/ar\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/abdullahsakkijha.com\/ar\/wp-json\/wp\/v2\/users\/333"}],"replies":[{"embeddable":true,"href":"https:\/\/abdullahsakkijha.com\/ar\/wp-json\/wp\/v2\/comments?post=11548"}],"version-history":[{"count":0,"href":"https:\/\/abdullahsakkijha.com\/ar\/wp-json\/wp\/v2\/pages\/11548\/revisions"}],"wp:attachment":[{"href":"https:\/\/abdullahsakkijha.com\/ar\/wp-json\/wp\/v2\/media?parent=11548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}